{"id":343618,"date":"2025-11-02T19:46:09","date_gmt":"2025-11-02T18:46:09","guid":{"rendered":"https:\/\/collection.galerie-gerdes.com\/?post_type=product&#038;p=343618"},"modified":"2025-11-02T20:44:11","modified_gmt":"2025-11-02T19:44:11","slug":"adliger-mit-degen-zeichnung-studie-gemaelde-von-r-fugger","status":"publish","type":"product","link":"https:\/\/collection.galerie-gerdes.com\/da\/p\/adliger-mit-degen-zeichnung-studie-gemaelde-von-r-fugger\/","title":{"rendered":"Adliger mit Degen | Zeichnung\/Studie | Gem\u00e4lde von R. Fugger"},"content":{"rendered":"<p>R. Fugger (*um 1895; t\u00e4tig bis etwa 1974) war ein deutscher Maler, der \u00fcberwiegend als Landschafts- und Genremaler arbeitete. Seine k\u00fcnstlerische T\u00e4tigkeit erstreckte sich auf S\u00fcddeutschland und Wien, wo er zwischen etwa 1910 und 1974 aktiv war. Fugger schuf vor allem Landschaftsdarstellungen sowie figurenreiche Szenen und widmete sich in seinem Werk sowohl der Darstellung der Natur als auch des allt\u00e4glichen Lebens in l\u00e4ndlicher und st\u00e4dtischer Umgebung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R. Fugger (XX)<\/p>\n","protected":false},"featured_media":345044,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[15,52,179,15281,266],"product_tag":[],"class_list":{"0":"post-343618","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-oesterreichisch","7":"product_cat-20th-century","8":"product_cat-gemaelde","9":"product_cat-r-fugger","10":"product_cat-zeichnung","11":"desktop-align-center","12":"tablet-align-left","13":"mobile-align-left","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/product\/343618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/media\/345044"}],"wp:attachment":[{"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/media?parent=343618"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/product_brand?post=343618"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/product_cat?post=343618"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/da\/wp-json\/wp\/v2\/product_tag?post=343618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}