{"id":14298,"count":1,"description":"Ernst Graner (* 25. September 1865 in Werdau, Sachsen; \u2020 27. November 1943 in Wien) war ein \u00f6sterreichischer Aquarellist.\n\nEr studierte an der Wiener Akademie unter Eduard von Lichtenfels und stellte seit 1890 auf Wiener Ausstellungen Landschaftsgem\u00e4lde aus. Graner gilt als einer der bedeutendsten Wiener Aquarellisten seiner Zeit. Seine zahlreichen Aquarelle zeigen Ansichten mit reichen Staffagen aus Wien, vor allem die Hofburg und Schloss Sch\u00f6nbrunn mit Ausfahrten des Kaisers Franz Joseph. Einige der abgebildeten Geb\u00e4ude existieren nicht mehr, wie beispielsweise die Wiener Rotunde, der Philipphof oder das Wiener Stadttheater. In seiner Fr\u00fchzeit malte Graner auch Genreszenen.\n\nGraner war mit Maria Kastler, der Tochter eines Hammerschmieds aus Klam (Klamschlucht), verheiratet und hielt sich zeitweise dort auf. Das Bildnis Maria in der Schlucht tr\u00e4gt die Z\u00fcge seiner Frau. Ein von ihm gemaltes Fresko an der Hammerschmiede in der Klamschlucht auf dem Kulturwanderweg August Strindbergweg-Klamschlucht zeigt seinen Schwiegervater bei dessen Arbeit. Er wurde in einem ehrenhalber gewidmeten Grab am Wiener Zentralfriedhof bestattet.\n\n1961 wurde in Wien-Liesing (23. Bezirk) die Granergasse nach ihm benannt.\n\nGraners Werke sind unter anderem auch im Historischen Museum der Stadt Wien ausgestellt.","link":"https:\/\/collection.galerie-gerdes.com\/de\/c\/kuenstler\/ernst-graner\/","name":"Ernst Graner","slug":"ernst-graner","taxonomy":"product_cat","parent":44,"meta":[],"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/de\/wp-json\/wp\/v2\/product_cat\/14298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/de\/wp-json\/wp\/v2\/product_cat\/44"}],"wp:post_type":[{"href":"https:\/\/collection.galerie-gerdes.com\/de\/wp-json\/wp\/v2\/product?product_cat=14298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}