{"id":253749,"date":"2024-10-23T22:37:25","date_gmt":"2024-10-23T20:37:25","guid":{"rendered":"https:\/\/www.collection.galerie-gerdes.com\/?post_type=product&#038;p=253749"},"modified":"2024-11-15T13:50:08","modified_gmt":"2024-11-15T12:50:08","slug":"dame-mit-stock-zeichnung-studie-von-josef-oberberger","status":"publish","type":"product","link":"https:\/\/collection.galerie-gerdes.com\/fr\/p\/dame-mit-stock-zeichnung-studie-von-josef-oberberger\/","title":{"rendered":"\u00ab\u00a0Herbst\u00a0\u00bb, Dame mit Stock | Zeichnung\/Studie von Josef Oberberger"},"content":{"rendered":"<p>Josef Oberberger (* 21. Dezember 1905 in Etzenricht, Oberpfalz; \u2020 2. Dezember 1994 in Kreuth) war ein vielseitiger deutscher K\u00fcnstler: Maler, Grafiker, Zeichner, Karikaturist, Glasmaler und Professor an der Kunstakademie M\u00fcnchen. Geboren als Sohn eines Stationsdieners, wuchs Oberberger in Grass bei Regensburg auf. Von 1915 bis 1921 besuchte er das Gymnasium in Regensburg und war Mitglied der Regensburger Domspatzen. Nach einer Lehre als Glasmaler bei der Hofglasmalerei Georg Schneider studierte er ab 1925 an der Akademie der Bildenden K\u00fcnste M\u00fcnchen bei Olaf Gulbransson, dessen Meistersch\u00fcler und lebenslanger Freund er wurde. Er heiratete 1939 Mathilde Schmeckenbecher, die er w\u00e4hrend seiner Studienzeit in M\u00fcnchen kennengelernt hatte.<\/p>\n<p>Nach Abschluss seines Studiums arbeitete Oberberger als Leiter der Glasmalereiklasse an der Akademie und als freier K\u00fcnstler. W\u00e4hrend des Zweiten Weltkriegs diente er zun\u00e4chst als Infanterist in Frankreich und Russland und wurde zum Kriegszeichner ernannt. Parallel dazu war er am Schutz mittelalterlicher Glasfenster des Naumburger Doms beteiligt. Nach dem Krieg kehrte Oberberger an die Kunstakademie M\u00fcnchen zur\u00fcck, wo er bis zu seinem Ruhestand 1973 als Professor t\u00e4tig war. Trotz seiner Ablehnung der NSDAP und der nationalsozialistischen Kunstausstellungen erhielt er erst 1952 eine feste Professur. Im Laufe seiner Karriere unternahm er zahlreiche Studienreisen und pr\u00e4gte als Lehrer \u00fcber 400 Sch\u00fcler. Sein vielf\u00e4ltiges Werk, das von Glasmalerei \u00fcber Grafik bis hin zu monumentalen Wandbildern reichte, wurde teilweise im Krieg zerst\u00f6rt, blieb jedoch ein bedeutender Beitrag zur Kunst des 20. Jahrhunderts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Josef Oberberger (1905-1994)<\/p>\n","protected":false},"featured_media":253754,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[52,25,420,179,14409,266],"product_tag":[],"class_list":{"0":"post-253749","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-20th-century","7":"product_cat-deutsch","8":"product_cat-figuren","9":"product_cat-gemaelde","10":"product_cat-josef-oberberger","11":"product_cat-zeichnung","12":"desktop-align-center","13":"tablet-align-left","14":"mobile-align-left","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product\/253749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/media\/253754"}],"wp:attachment":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/media?parent=253749"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_brand?post=253749"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_cat?post=253749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_tag?post=253749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}