{"id":4759,"count":0,"description":"Carl Blum est n\u00e9 \u00e0 Fribourg le 1er novembre 1888 et est mort \u00e0 Balingen le 31 d\u00e9cembre 1953. Il commence ses \u00e9tudes \u00e0 l'Acad\u00e9mie des beaux-arts de Karlsruhe vers 1910 aupr\u00e8s de professeurs renomm\u00e9s tels que Ludwig Dill, Wilhelm Tr\u00fcbner et Hans Thoma. Pendant la Premi\u00e8re Guerre mondiale, il sert de 1914 \u00e0 1918 et est bless\u00e9.\n\nBlum est membre du groupe d'artistes \u00ab Zunft zur Arche \u00bb \u00e0 Karlsruhe et participe aux expositions du groupe entre 1931 et 1934. En 1934, il participe \u00e9galement \u00e0 l'exposition \u00ab Art sud-allemand \u00e0 Munich \u00bb \u00e0 la Neue Pinakothek.\n\nEn 1940, il s'installe d\u00e9finitivement \u00e0 Balingen, apr\u00e8s y avoir pass\u00e9 les mois d'\u00e9t\u00e9. De 1942 \u00e0 1943, il enseigne le dessin \u00e0 l'Oberrealschule.","link":"https:\/\/collection.galerie-gerdes.com\/fr\/c\/artiste\/carl-blum-fr\/","name":"Carl Blum","slug":"carl-blum-fr","taxonomy":"product_cat","parent":1860,"meta":[],"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_cat\/4759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product_cat\/1860"}],"wp:post_type":[{"href":"https:\/\/collection.galerie-gerdes.com\/fr\/wp-json\/wp\/v2\/product?product_cat=4759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}