{"id":206031,"date":"2024-07-28T13:47:07","date_gmt":"2024-07-28T11:47:07","guid":{"rendered":"https:\/\/www.collection.galerie-gerdes.com\/?post_type=product&#038;p=206031"},"modified":"2024-08-16T22:09:30","modified_gmt":"2024-08-16T20:09:30","slug":"lesender-mann-1905-zeichnung-von-hans-fritsch-meggendorfer-blaetter-muenchen","status":"publish","type":"product","link":"https:\/\/collection.galerie-gerdes.com\/lt\/p\/lesender-mann-1905-zeichnung-von-hans-fritsch-meggendorfer-blaetter-muenchen\/","title":{"rendered":"Lesender Mann, 1905 | Zeichnung von Hans Fritsch | Meggendorfer-Bl\u00e4tter M\u00fcnchen"},"content":{"rendered":"<p>Hans Fritsch (1870-1945) war ein deutscher Maler aus Dresden. Als Sohn eines Musikdirektors begann er seine Ausbildung am Konservatorium in Dresden. Ab 1887 studierte er an der dortigen Akademie und schloss dieses Studium nach einer l\u00e4ngeren Unterbrechung im Jahr 1895 ab. Fritsch arbeitete als freischaffender K\u00fcnstler und nahm an zeitgen\u00f6ssischen Ausstellungen in ganz Deutschland teil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hans Fritsch (1870-1945)<\/p>\n","protected":false},"featured_media":206272,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[179,330,424,266],"product_tag":[],"class_list":["post-206031","product","type-product","status-publish","has-post-thumbnail","product_cat-gemaelde","product_cat-hans-fritsch","product_cat-karikaturen","product_cat-zeichnung","desktop-align-center","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/product\/206031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/media\/206272"}],"wp:attachment":[{"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/media?parent=206031"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/product_brand?post=206031"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/product_cat?post=206031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/lt\/wp-json\/wp\/v2\/product_tag?post=206031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}