{"id":5899,"count":0,"description":"","link":"https:\/\/collection.galerie-gerdes.com\/sk\/c\/umelci-sk\/e-gabzi-sk\/","name":"E. Gabzi","slug":"e-gabzi-sk","taxonomy":"product_cat","parent":1875,"meta":[],"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/sk\/wp-json\/wp\/v2\/product_cat\/5899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/sk\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/sk\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/sk\/wp-json\/wp\/v2\/product_cat\/1875"}],"wp:post_type":[{"href":"https:\/\/collection.galerie-gerdes.com\/sk\/wp-json\/wp\/v2\/product?product_cat=5899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}