{"id":10750,"count":0,"description":"\u5f7c\u5f97-\u79d1\u8d6b\uff081874 \u5e74 10 \u6708 8 \u65e5\u51fa\u751f\u4e8e\u4ee3\u5fb7\u6d77\u59c6\u9644\u8fd1\u7684\u672c\u626c\u7279\u5c14\uff0c1956 \u5e74 8 \u6708 10 \u65e5\u51fa\u751f\u4e8e\u91d1\u6885\u5c14\u4e01\u6839\uff09\u662f\u5fb7\u56fd\u4e00\u4f4d\u91cd\u8981\u7684\u753b\u5bb6\uff0c\u4ee5\u5176\u5177\u8c61\u4f5c\u54c1\u548c\u540e\u6765\u7684\u98ce\u666f\u753b\u800c\u95fb\u540d\u3002\n\n\u79d1\u8d6b\u51fa\u751f\u4e8e\u672c\u626c\u7279\u5c14\u7684 \u201cObere M\u00fchle\u201d\uff0c\u4ed6\u7684\u7236\u4eb2\u7ea6\u7ff0-\u79d1\u8d6b\uff08Johann Koch\uff09\u662f\u4e00\u540d\u94c1\u5320\u3002\u5728\u7ed8\u753b\u5b66\u6821\u63a5\u53d7\u4e86\u521d\u6b65\u57f9\u8bad\u540e\uff0c\u79d1\u8d6b\u8fdb\u5165\u6155\u5c3c\u9ed1\u7f8e\u672f\u5b66\u9662\u5b66\u4e60\u3002\u5728\u90a3\u91cc\uff0c\u4ed6\u5e08\u4ece Gabriel von Hackl \u6559\u6388\u548c Carl von Marr \u6559\u6388\u7b49\u4eba\u3002\n\n\u5728\u8ddf\u968f\u6d77\u56e0\u91cc\u5e0c-\u51af-\u7956\u683c\u5c14\uff08Heinrich von Z\u00fcgel\uff09\u6df1\u9020\u540e\uff0c\u79d1\u8d6b\u5728\u6155\u5c3c\u9ed1\u3001\u67cf\u6797\u548c\u745e\u58eb\u5de5\u4f5c\u3002\u901a\u8fc7\u5728\u6155\u5c3c\u9ed1\uff081908 \u5e74\uff09\u3001\u67cf\u6797\u5206\u79bb\u6d3e\uff081911\/12 \u5e74\uff09\u3001\u5df4\u585e\u5c14\uff081912 \u5e74\uff09\u548c\u66fc\u6d77\u59c6\uff081913 \u5e74\uff09\u4e3e\u529e\u7684\u5c55\u89c8\uff0c\u4ed6\u5f88\u5feb\u83b7\u5f97\u4e86\u8ba4\u53ef\u30021914 \u5e74\uff0c\u4ed6\u79bb\u5f00\u5fb7\u56fd\uff0c\u5728\u7f8e\u56fd\u5446\u4e86\u516b\u5e74\uff0c\u5c24\u5176\u662f\u5728\u7ebd\u7ea6\u5dde\u548c\u65b0\u6cfd\u897f\u5dde\uff0c\u5e76\u6210\u4e3a\u72ec\u7acb\u827a\u672f\u5bb6\u534f\u4f1a\u7684\u6210\u5458\u3002\n\n1922 \u5e74\uff0c\u79d1\u8d6b\u56de\u5230\u5fb7\u56fd\uff0c\u5b9a\u5c45\u5728\u91d1\u6885\u5c14\u4e01\u6839\u3002\u5728\u90a3\u91cc\uff0c\u4ed6\u88ab\u4efb\u547d\u4e3a\u5e02\u957f\uff0c\u5e76\u4e8e 1954 \u5e74\u88ab\u6388\u4e88\u8363\u8a89\u5e02\u6c11\u79f0\u53f7\u3002\u4ed6\u7684\u65e9\u671f\u4f5c\u54c1\u4e3b\u8981\u662f\u5f62\u8c61\u63cf\u7ed8\uff0c\u540e\u6765\u5219\u8d8a\u6765\u8d8a\u591a\u5730\u6295\u8eab\u4e8e\u98ce\u666f\u753b\u521b\u4f5c\u3002","link":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/c\/%e8%89%ba%e6%9c%af%e5%ae%b6\/peter-koch-zh-hans\/","name":"Peter Koch","slug":"peter-koch-zh-hans","taxonomy":"product_cat","parent":10125,"meta":[],"_links":{"self":[{"href":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/wp-json\/wp\/v2\/product_cat\/10750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/wp-json\/wp\/v2\/product_cat\/10125"}],"wp:post_type":[{"href":"https:\/\/collection.galerie-gerdes.com\/zh-hans\/wp-json\/wp\/v2\/product?product_cat=10750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}